
{"id":370637,"date":"2024-07-11T16:22:16","date_gmt":"2024-07-11T14:22:16","guid":{"rendered":"https:\/\/sscnapoli.it\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/"},"modified":"2024-07-11T19:13:13","modified_gmt":"2024-07-11T17:13:13","slug":"il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari","status":"publish","type":"post","link":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/","title":{"rendered":"Sgarbi heads to Bari on loan"},"content":{"rendered":"\n<p>SSC Napoli can confirm that Lorenzo Sgarbi has moved to Bari on a loan deal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SSC Napoli can confirm that Lorenzo Sgarbi has moved to Bari on a loan deal.<\/p>\n","protected":false},"author":12,"featured_media":366619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[],"class_list":{"0":"post-370637","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-transfer-market","8":"nebula-entry","9":"date-day-thursday","10":"date-ymd-2024-07-11","11":"date-month-july","12":"cat-id-93","13":"author-id-12","14":"multi-author","15":"has-featured-image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sgarbi heads to Bari on loan - SSC Napoli<\/title>\n<meta name=\"description\" content=\"SSC Napoli can confirm that Lorenzo Sgarbi has moved to Bari on a loan deal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sgarbi heads to Bari on loan - SSC Napoli\" \/>\n<meta property=\"og:description\" content=\"SSC Napoli can confirm that Lorenzo Sgarbi has moved to Bari on a loan deal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/\" \/>\n<meta property=\"og:site_name\" content=\"SSC Napoli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SSCNapoli\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T14:22:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T17:13:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2024\/06\/NAPOLI-MARADONA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruno Marra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SSCNapoli\" \/>\n<meta name=\"twitter:site\" content=\"@SSCNapoli\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Marra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/\"},\"author\":{\"name\":\"Bruno Marra\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#\\\/schema\\\/person\\\/344117c75c5bc4f35dcc9f5de5273982\"},\"headline\":\"Sgarbi heads to Bari on loan\",\"datePublished\":\"2024-07-11T14:22:16+00:00\",\"dateModified\":\"2024-07-11T17:13:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/\"},\"wordCount\":21,\"image\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/NAPOLI-MARADONA.jpg\",\"articleSection\":[\"Transfer market\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/\",\"url\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/\",\"name\":\"Sgarbi heads to Bari on loan - SSC Napoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/NAPOLI-MARADONA.jpg\",\"datePublished\":\"2024-07-11T14:22:16+00:00\",\"dateModified\":\"2024-07-11T17:13:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#\\\/schema\\\/person\\\/344117c75c5bc4f35dcc9f5de5273982\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/NAPOLI-MARADONA.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/NAPOLI-MARADONA.jpg\",\"width\":1440,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sgarbi heads to Bari on loan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/\",\"name\":\"SSC Napoli\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#\\\/schema\\\/person\\\/344117c75c5bc4f35dcc9f5de5273982\",\"name\":\"Bruno Marra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c7da890bdb5f972e7c821e28a24f20c2c20d5e5a1fec13d27be23a40e94286d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c7da890bdb5f972e7c821e28a24f20c2c20d5e5a1fec13d27be23a40e94286d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c7da890bdb5f972e7c821e28a24f20c2c20d5e5a1fec13d27be23a40e94286d?s=96&d=mm&r=g\",\"caption\":\"Bruno Marra\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sgarbi heads to Bari on loan - SSC Napoli","description":"SSC Napoli can confirm that Lorenzo Sgarbi has moved to Bari on a loan deal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/","og_locale":"en_US","og_type":"article","og_title":"Sgarbi heads to Bari on loan - SSC Napoli","og_description":"SSC Napoli can confirm that Lorenzo Sgarbi has moved to Bari on a loan deal.","og_url":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/","og_site_name":"SSC Napoli","article_publisher":"https:\/\/www.facebook.com\/SSCNapoli","article_published_time":"2024-07-11T14:22:16+00:00","article_modified_time":"2024-07-11T17:13:13+00:00","og_image":[{"width":1440,"height":940,"url":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2024\/06\/NAPOLI-MARADONA.jpg","type":"image\/jpeg"}],"author":"Bruno Marra","twitter_card":"summary_large_image","twitter_creator":"@SSCNapoli","twitter_site":"@SSCNapoli","twitter_misc":{"Written by":"Bruno Marra","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/#article","isPartOf":{"@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/"},"author":{"name":"Bruno Marra","@id":"https:\/\/sscnapoli.it\/en\/#\/schema\/person\/344117c75c5bc4f35dcc9f5de5273982"},"headline":"Sgarbi heads to Bari on loan","datePublished":"2024-07-11T14:22:16+00:00","dateModified":"2024-07-11T17:13:13+00:00","mainEntityOfPage":{"@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/"},"wordCount":21,"image":{"@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2024\/06\/NAPOLI-MARADONA.jpg","articleSection":["Transfer market"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/","url":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/","name":"Sgarbi heads to Bari on loan - SSC Napoli","isPartOf":{"@id":"https:\/\/sscnapoli.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/#primaryimage"},"image":{"@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2024\/06\/NAPOLI-MARADONA.jpg","datePublished":"2024-07-11T14:22:16+00:00","dateModified":"2024-07-11T17:13:13+00:00","author":{"@id":"https:\/\/sscnapoli.it\/en\/#\/schema\/person\/344117c75c5bc4f35dcc9f5de5273982"},"breadcrumb":{"@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/#primaryimage","url":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2024\/06\/NAPOLI-MARADONA.jpg","contentUrl":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2024\/06\/NAPOLI-MARADONA.jpg","width":1440,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/sscnapoli.it\/en\/il-napoli-ufficializza-la-cessione-in-prestito-di-sgarbi-al-bari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sscnapoli.it\/en\/"},{"@type":"ListItem","position":2,"name":"Sgarbi heads to Bari on loan"}]},{"@type":"WebSite","@id":"https:\/\/sscnapoli.it\/en\/#website","url":"https:\/\/sscnapoli.it\/en\/","name":"SSC Napoli","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sscnapoli.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sscnapoli.it\/en\/#\/schema\/person\/344117c75c5bc4f35dcc9f5de5273982","name":"Bruno Marra","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6c7da890bdb5f972e7c821e28a24f20c2c20d5e5a1fec13d27be23a40e94286d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c7da890bdb5f972e7c821e28a24f20c2c20d5e5a1fec13d27be23a40e94286d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c7da890bdb5f972e7c821e28a24f20c2c20d5e5a1fec13d27be23a40e94286d?s=96&d=mm&r=g","caption":"Bruno Marra"}}]}},"_links":{"self":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts\/370637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/comments?post=370637"}],"version-history":[{"count":1,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts\/370637\/revisions"}],"predecessor-version":[{"id":370638,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts\/370637\/revisions\/370638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/media\/366619"}],"wp:attachment":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/media?parent=370637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/categories?post=370637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/tags?post=370637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}