
{"id":611500,"date":"2026-04-17T11:00:00","date_gmt":"2026-04-17T09:00:00","guid":{"rendered":"https:\/\/sscnapoli.it\/ssc-napoli-in-campo-contro-le-discriminazioni\/"},"modified":"2026-04-17T21:29:09","modified_gmt":"2026-04-17T19:29:09","slug":"ssc-napoli-in-campo-contro-le-discriminazioni","status":"publish","type":"post","link":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/","title":{"rendered":"SSC Napoli takes the field against discrimination"},"content":{"rendered":"\n<p>The match between Napoli and Lazio will be preceded by <strong>SSC Napoli<\/strong>\u2019s initiative dedicated to inclusion and countering every form of discrimination. The players will take the field before kick-off together with children with a migration background from local schools.<\/p>\n\n\n\n<p>The goal of the initiative is to send a message through football and at &nbsp;the Stadio Maradona, a symbolic place where children will be the protagonists of a socially significant event centred on integration and equal opportunities.<\/p>\n\n\n\n<p>SSC Napoli would like to thank the <strong>Municipality of<\/strong> <strong>Naples <\/strong>and, in particular, its <strong>Department for Social Policies,<\/strong> for their collaboration and support in selecting the associations to involve in the initiative, thus allowing children to take part in such a meaningful experience.<\/p>\n\n\n\n<p>The children involved are the authentic face of a multi-cultural, vibrant and inclusive city, where diversity is an asset that leads to collective growth. By walking onto the pitch with the Napoli players, they took centre stage, showing that Naples is a open and welcoming community.<\/p>\n\n\n\n<p><strong>Chiara Marciani, City Councillor for Social Policies<\/strong>, had this to say: \u201cThis initiative aims to strongly reassert our constant commitment against every form of discrimination. Sport, and football in particular, has the chance to speak directly to people and spread positive values. We want this message to be heard loud and clear above all by the new generations. I want to thank SSC Napoli for their attention to this topic and for creating such a significant and unforgettable experience for these children, by offering them the chance to experience a unique moment first-hand in a very important sporting venue.\u201d<\/p>\n\n\n\n<p><strong>Tommaso Bianchini, General Manager \u2013 Business Area of SSC Napoli<\/strong>, stated: \u201cSSC Napoli believes in the social value of football and in its ability to speak to all communities. The purpose of this initiative is to send once again a message of inclusion through the symbolism of players taking the field alongside these children. We would like to thank the Department for Social Policies of the Municipality of Naples for their collaboration in this initiative.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The match between Napoli and Lazio will be preceded by SSC Napoli\u2019s initiative dedicated to inclusion and countering every form of discrimination. The players will take the field before kick-off together with children with a migration background from local schools. The goal of the initiative is to send a message through football and at &nbsp;the [&hellip;]<\/p>\n","protected":false},"author":197618,"featured_media":611326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[],"class_list":{"0":"post-611500","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"nebula-entry","9":"date-day-friday","10":"date-ymd-2026-04-17","11":"date-month-april","12":"cat-id-100","13":"author-id-197618","14":"multi-author","15":"has-featured-image"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SSC Napoli takes the field against discrimination - SSC Napoli<\/title>\n<meta name=\"description\" content=\"The match between Napoli and Lazio will be preceded by SSC Napoli\u2019s initiative dedicated to inclusion and countering every form of discrimination.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SSC Napoli takes the field against discrimination - SSC Napoli\" \/>\n<meta property=\"og:description\" content=\"The match between Napoli and Lazio will be preceded by SSC Napoli\u2019s initiative dedicated to inclusion and countering every form of discrimination. The players will take the field before kick-off together with children with a migration background from local schools. The goal of the initiative is to send a message through football and at &nbsp;the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"SSC Napoli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SSCNapoli\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T19:29:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2026\/04\/Discriminazioni-1440x940.jpg.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giuseppe Lombardi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SSCNapoli\" \/>\n<meta name=\"twitter:site\" content=\"@SSCNapoli\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giuseppe Lombardi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/\"},\"author\":{\"name\":\"Giuseppe Lombardi\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#\\\/schema\\\/person\\\/5dcb7390f6e6dacea3d2a5aa13e4df81\"},\"headline\":\"SSC Napoli takes the field against discrimination\",\"datePublished\":\"2026-04-17T09:00:00+00:00\",\"dateModified\":\"2026-04-17T19:29:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/\"},\"wordCount\":348,\"image\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Discriminazioni-1440x940.jpg.jpeg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/\",\"url\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/\",\"name\":\"SSC Napoli takes the field against discrimination - SSC Napoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Discriminazioni-1440x940.jpg.jpeg\",\"datePublished\":\"2026-04-17T09:00:00+00:00\",\"dateModified\":\"2026-04-17T19:29:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#\\\/schema\\\/person\\\/5dcb7390f6e6dacea3d2a5aa13e4df81\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Discriminazioni-1440x940.jpg.jpeg\",\"contentUrl\":\"https:\\\/\\\/cdn.sscnapoli.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Discriminazioni-1440x940.jpg.jpeg\",\"width\":1440,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/ssc-napoli-in-campo-contro-le-discriminazioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SSC Napoli takes the field against discrimination\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/\",\"name\":\"SSC Napoli\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sscnapoli.it\\\/en\\\/#\\\/schema\\\/person\\\/5dcb7390f6e6dacea3d2a5aa13e4df81\",\"name\":\"Giuseppe Lombardi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01be81df8b858b7e615ca561d2dbd7d06019628d79e272b9a4e52f96389d7c62?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01be81df8b858b7e615ca561d2dbd7d06019628d79e272b9a4e52f96389d7c62?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01be81df8b858b7e615ca561d2dbd7d06019628d79e272b9a4e52f96389d7c62?s=96&d=mm&r=g\",\"caption\":\"Giuseppe Lombardi\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SSC Napoli takes the field against discrimination - SSC Napoli","description":"The match between Napoli and Lazio will be preceded by SSC Napoli\u2019s initiative dedicated to inclusion and countering every form of discrimination.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/","og_locale":"en_US","og_type":"article","og_title":"SSC Napoli takes the field against discrimination - SSC Napoli","og_description":"The match between Napoli and Lazio will be preceded by SSC Napoli\u2019s initiative dedicated to inclusion and countering every form of discrimination. The players will take the field before kick-off together with children with a migration background from local schools. The goal of the initiative is to send a message through football and at &nbsp;the [&hellip;]","og_url":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/","og_site_name":"SSC Napoli","article_publisher":"https:\/\/www.facebook.com\/SSCNapoli","article_published_time":"2026-04-17T09:00:00+00:00","article_modified_time":"2026-04-17T19:29:09+00:00","og_image":[{"width":1440,"height":940,"url":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2026\/04\/Discriminazioni-1440x940.jpg.jpeg","type":"image\/jpeg"}],"author":"Giuseppe Lombardi","twitter_card":"summary_large_image","twitter_creator":"@SSCNapoli","twitter_site":"@SSCNapoli","twitter_misc":{"Written by":"Giuseppe Lombardi","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/#article","isPartOf":{"@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/"},"author":{"name":"Giuseppe Lombardi","@id":"https:\/\/sscnapoli.it\/en\/#\/schema\/person\/5dcb7390f6e6dacea3d2a5aa13e4df81"},"headline":"SSC Napoli takes the field against discrimination","datePublished":"2026-04-17T09:00:00+00:00","dateModified":"2026-04-17T19:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/"},"wordCount":348,"image":{"@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2026\/04\/Discriminazioni-1440x940.jpg.jpeg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/","url":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/","name":"SSC Napoli takes the field against discrimination - SSC Napoli","isPartOf":{"@id":"https:\/\/sscnapoli.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/#primaryimage"},"image":{"@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2026\/04\/Discriminazioni-1440x940.jpg.jpeg","datePublished":"2026-04-17T09:00:00+00:00","dateModified":"2026-04-17T19:29:09+00:00","author":{"@id":"https:\/\/sscnapoli.it\/en\/#\/schema\/person\/5dcb7390f6e6dacea3d2a5aa13e4df81"},"breadcrumb":{"@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/#primaryimage","url":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2026\/04\/Discriminazioni-1440x940.jpg.jpeg","contentUrl":"https:\/\/cdn.sscnapoli.it\/wp-content\/uploads\/2026\/04\/Discriminazioni-1440x940.jpg.jpeg","width":1440,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/sscnapoli.it\/en\/ssc-napoli-in-campo-contro-le-discriminazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sscnapoli.it\/en\/"},{"@type":"ListItem","position":2,"name":"SSC Napoli takes the field against discrimination"}]},{"@type":"WebSite","@id":"https:\/\/sscnapoli.it\/en\/#website","url":"https:\/\/sscnapoli.it\/en\/","name":"SSC Napoli","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sscnapoli.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sscnapoli.it\/en\/#\/schema\/person\/5dcb7390f6e6dacea3d2a5aa13e4df81","name":"Giuseppe Lombardi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/01be81df8b858b7e615ca561d2dbd7d06019628d79e272b9a4e52f96389d7c62?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01be81df8b858b7e615ca561d2dbd7d06019628d79e272b9a4e52f96389d7c62?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01be81df8b858b7e615ca561d2dbd7d06019628d79e272b9a4e52f96389d7c62?s=96&d=mm&r=g","caption":"Giuseppe Lombardi"}}]}},"_links":{"self":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts\/611500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/users\/197618"}],"replies":[{"embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/comments?post=611500"}],"version-history":[{"count":1,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts\/611500\/revisions"}],"predecessor-version":[{"id":611501,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/posts\/611500\/revisions\/611501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/media\/611326"}],"wp:attachment":[{"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/media?parent=611500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/categories?post=611500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sscnapoli.it\/en\/wp-json\/wp\/v2\/tags?post=611500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}